
{"id":6301,"date":"2022-09-12T15:33:39","date_gmt":"2022-09-12T15:33:39","guid":{"rendered":"https:\/\/www.aguram.org\/aguram\/?p=6301"},"modified":"2024-04-08T08:15:10","modified_gmt":"2024-04-08T08:15:10","slug":"carnet-dactualite-hors-serie-6-schemas-sur-les-friches","status":"publish","type":"post","link":"https:\/\/www.aguram.org\/aguram\/carnet-dactualite-hors-serie-6-schemas-sur-les-friches\/","title":{"rendered":"CARNET D\u2019ACTUALIT\u00c9 HORS S\u00c9RIE \/ 6 SCH\u00c9MAS SUR LES FRICHES"},"content":{"rendered":"\n<p><strong>Depuis la loi Climat &amp; r\u00e9silience qui fixe un objectif de z\u00e9ro artificialisation nette&nbsp;d\u2019ici 2050, le foncier et plus globalement les sols&nbsp;se retrouvent au c\u0153ur des&nbsp;probl\u00e9matiques d\u2019am\u00e9nagement et d\u2019urbanisme. Dans ce&nbsp;contexte, les espaces en friche&nbsp;permettront sans doute de faire \u00e9merger&nbsp;des projets b\u00e9n\u00e9fiques pour les&nbsp;territoires, qu\u2019il s\u2019agisse de renouvellement&nbsp;urbain, de d\u00e9veloppement \u00e9conomique ou de valorisation de la biodiversit\u00e9.&nbsp;<\/strong><\/p>\n\n\n\n<p><strong><strong>D\u00e9couvrez d\u00e8s \u00e0 pr\u00e9sent<\/strong> notre nouveau Carnet d&rsquo;actualit\u00e9 hors s\u00e9rie consacr\u00e9 aux friches et \u00e0 leur requalification<\/strong><strong> !<\/strong><\/p>\n\n\n\n<!--more-->\n\n\n\n<p>L\u2019enjeu de la requalification des friches fait d\u00e9sormais partie des l\u00e9gislations europ\u00e9ennes et fran\u00e7aises. Depuis 2021, la loi Climat &amp; r\u00e9silience incite les acteurs de l&rsquo;am\u00e9nagement \u00e0 \u00ab&nbsp;construire la ville sur la ville \u00bb, c&rsquo;est \u00e0 dire \u00e0 densifier des espaces d\u00e9j\u00e0 urbanis\u00e9s en s\u2019appuyant notamment sur les gisements fonciers essentiels que sont les friches.<\/p>\n\n\n\n<p>\u00c0 travers 6 sch\u00e9mas de synth\u00e8se, ce Carnet d&rsquo;actualit\u00e9 hors s\u00e9rie vous propose\u00a0une approche imag\u00e9e de la friche, de sa gen\u00e8se \u00e0 sa requalification, en s\u2019int\u00e9ressant aux complexit\u00e9s du renouvellement de la ville et des villages et aux diff\u00e9rents moyens d\u2019intervention.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"623\" src=\"https:\/\/www.aguram.org\/wp-content\/uploads\/2022\/09\/Capture-CA-friches_schema-1-1024x623.png\" alt=\"\" class=\"wp-image-6306\" srcset=\"https:\/\/www.aguram.org\/wp-content\/uploads\/2022\/09\/Capture-CA-friches_schema-1-1024x623.png 1024w, https:\/\/www.aguram.org\/wp-content\/uploads\/2022\/09\/Capture-CA-friches_schema-1-300x182.png 300w, https:\/\/www.aguram.org\/wp-content\/uploads\/2022\/09\/Capture-CA-friches_schema-1-768x467.png 768w, https:\/\/www.aguram.org\/wp-content\/uploads\/2022\/09\/Capture-CA-friches_schema-1.png 1148w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>N\u2019h\u00e9sitez pas \u00e0 partager largement cette publication, \u00e0 visiter r\u00e9guli\u00e8rement ce site et \u00e0 vous abonner \u00e0 nos pages sur les r\u00e9seaux sociaux pour suivre notre actualit\u00e9 et nos travaux.<\/p>\n\n\n\n<p>Retrouvez \u00e9galement notre <a href=\"https:\/\/www.aguram.org\/aguram\/hors-serie-carnet-dactualite-6-schemas-pour-comprendre-le-volet-urbanisme-de-la-loi-climat-resilience\/\" target=\"_blank\" rel=\"noreferrer noopener\">Carnet d&rsquo;actualit\u00e9 hors s\u00e9rie sur la loi Climat &amp; r\u00e9silience<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depuis la loi Climat &amp; r\u00e9silience qui fixe un objectif de z\u00e9ro artificialisation nette&nbsp;d\u2019ici 2050, le foncier et plus globalement les sols&nbsp;se retrouvent au c\u0153ur des&nbsp;probl\u00e9matiques d\u2019am\u00e9nagement et d\u2019urbanisme. Dans ce&nbsp;contexte, les espaces en friche&nbsp;permettront sans doute de faire \u00e9merger&nbsp;des projets b\u00e9n\u00e9fiques pour les&nbsp;territoires, qu\u2019il s\u2019agisse de renouvellement&nbsp;urbain, de d\u00e9veloppement \u00e9conomique ou de valorisation de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":6304,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,911,53,79,80,51,94],"tags":[697,704,1025,832,703],"class_list":["post-6301","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aguram","category-carnet-dactualite","category-cooperations-territoriales","category-economie-attractivite","category-environnement-energie-climat","category-planification-foncier","category-projets-urbains","tag-carnet-2","tag-friches-2","tag-loi-climat-et-resilience","tag-sobriete-fonciere","tag-zan-2"],"jetpack_featured_media_url":"https:\/\/www.aguram.org\/wp-content\/uploads\/2022\/09\/Capture-CA-friches-e1662715564462.png","_links":{"self":[{"href":"https:\/\/www.aguram.org\/aguram\/wp-json\/wp\/v2\/posts\/6301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aguram.org\/aguram\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aguram.org\/aguram\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aguram.org\/aguram\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aguram.org\/aguram\/wp-json\/wp\/v2\/comments?post=6301"}],"version-history":[{"count":8,"href":"https:\/\/www.aguram.org\/aguram\/wp-json\/wp\/v2\/posts\/6301\/revisions"}],"predecessor-version":[{"id":8125,"href":"https:\/\/www.aguram.org\/aguram\/wp-json\/wp\/v2\/posts\/6301\/revisions\/8125"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aguram.org\/aguram\/wp-json\/wp\/v2\/media\/6304"}],"wp:attachment":[{"href":"https:\/\/www.aguram.org\/aguram\/wp-json\/wp\/v2\/media?parent=6301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aguram.org\/aguram\/wp-json\/wp\/v2\/categories?post=6301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aguram.org\/aguram\/wp-json\/wp\/v2\/tags?post=6301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}