
{"id":2601,"date":"2019-01-02T05:59:05","date_gmt":"2019-01-02T05:59:05","guid":{"rendered":"https:\/\/www.aguram.org\/?p=2601"},"modified":"2019-08-02T12:14:56","modified_gmt":"2019-08-02T12:14:56","slug":"habiter-le-pays-orne-moselle","status":"publish","type":"post","link":"https:\/\/www.aguram.org\/aguram\/habiter-le-pays-orne-moselle\/","title":{"rendered":"Reper&rsquo;Habitat \/ Habiter le Pays Orne-Moselle"},"content":{"rendered":"\n<p><strong>Territoire marqu\u00e9 par la crise sid\u00e9rurgique, la CCPOM amorce depuis 2009, une relance d\u00e9mographique : d\u2019importantes op\u00e9rations de logements construites dans les communes du plateau et des coteaux expliquent cette progression. Le march\u00e9 du logement reste plut\u00f4t accessible pour des m\u00e9nages souvent modestes, notamment dans la vall\u00e9e.<\/strong><\/p>\n\n\n\n<!--more-->\n\n\n\n<p>La requalification du parc ancien, la diversification de l\u2019offre de logements, la ma\u00eetrise de l\u2019urbanisation et la prise en charge des publics aux besoins sp\u00e9cifiques restent des enjeux majeurs pour l\u2019avenir. Ce Rep\u00e8r\u2019Habitat consacr\u00e9 au diagnostic r\u00e9alis\u00e9 dans le cadre du Programme Local de l\u2019Habitat (PLH) de la Communaut\u00e9 de Communes du Pays Orne-Moselle, en cours de r\u00e9vision.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Territoire marqu\u00e9 par la crise sid\u00e9rurgique, la CCPOM amorce depuis 2009, une relance d\u00e9mographique : d\u2019importantes op\u00e9rations de logements construites dans les communes du plateau et des coteaux expliquent cette progression. Le march\u00e9 du logement reste plut\u00f4t accessible pour des m\u00e9nages souvent modestes, notamment dans la vall\u00e9e.<\/p>\n","protected":false},"author":7,"featured_media":2602,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[50],"tags":[295,292,177,296,304,159,294,293],"class_list":["post-2601","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-habitat-societe","tag-ccpom","tag-demographie","tag-habitat","tag-pays-orne-moselle","tag-plh","tag-reper","tag-reper-habitat","tag-reperhabitat"],"jetpack_featured_media_url":"https:\/\/www.aguram.org\/wp-content\/uploads\/2019\/07\/Reper_Habitat_CCPOM_AGURAM_mars2019_Page_1.jpg","_links":{"self":[{"href":"https:\/\/www.aguram.org\/aguram\/wp-json\/wp\/v2\/posts\/2601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aguram.org\/aguram\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aguram.org\/aguram\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aguram.org\/aguram\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aguram.org\/aguram\/wp-json\/wp\/v2\/comments?post=2601"}],"version-history":[{"count":2,"href":"https:\/\/www.aguram.org\/aguram\/wp-json\/wp\/v2\/posts\/2601\/revisions"}],"predecessor-version":[{"id":2892,"href":"https:\/\/www.aguram.org\/aguram\/wp-json\/wp\/v2\/posts\/2601\/revisions\/2892"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aguram.org\/aguram\/wp-json\/wp\/v2\/media\/2602"}],"wp:attachment":[{"href":"https:\/\/www.aguram.org\/aguram\/wp-json\/wp\/v2\/media?parent=2601"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aguram.org\/aguram\/wp-json\/wp\/v2\/categories?post=2601"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aguram.org\/aguram\/wp-json\/wp\/v2\/tags?post=2601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}